{"id":2723,"date":"2024-02-06T11:56:16","date_gmt":"2024-02-06T11:56:16","guid":{"rendered":"https:\/\/wdtkitty.wpengine.com\/?post_type=product&amp;p=2723"},"modified":"2026-05-13T08:47:11","modified_gmt":"2026-05-13T08:47:11","slug":"belted-maxi-dress","status":"publish","type":"product","link":"https:\/\/maisonellej.co.uk\/index.php\/product\/belted-maxi-dress\/","title":{"rendered":"Belted Maxi Dress"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2723\" class=\"elementor elementor-2723\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a659943 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a659943\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe7d5f8\" data-id=\"fe7d5f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dadd55f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dadd55f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"wdt-sticky-column elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-04fc3f4\" data-wdt-settings=\"{&quot;id&quot;:&quot;04fc3f4&quot;,&quot;sticky&quot;:true,&quot;topSpacing&quot;:50,&quot;bottomSpacing&quot;:50,&quot;stickyOn&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;],&quot;overflowHidden&quot;:false}\" data-id=\"04fc3f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d15a13c wdt-cst-thumb-right elementor-invisible elementor-widget elementor-widget-wdt-shop-product-single-images-carousel\" data-id=\"d15a13c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_slidesperview&quot;:&quot;1&quot;,&quot;carousel_slidesperview_laptop&quot;:&quot;1&quot;,&quot;carousel_slidesperview_tablet_extra&quot;:&quot;1&quot;,&quot;carousel_slidesperview_tablet&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;carousel_slidesperview_mobile_extra&quot;:1,&quot;carousel_slidesperview_mobile&quot;:1,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-images-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bf67b5a\" data-id=\"bf67b5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af1df72 elementor-invisible elementor-widget elementor-widget-wdt-shop-product-single-summary\" data-id=\"af1df72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-summary.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81097ef elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"81097ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d546ff8\" data-id=\"d546ff8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-056ec1f elementor-invisible elementor-widget elementor-widget-wdt-shop-product-single-summary\" data-id=\"056ec1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-summary.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ef3df27 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ef3df27\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-51d5299\" data-id=\"51d5299\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d39196 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-wdt-shop-product-single-summary\" data-id=\"0d39196\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-summary.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3bdeed elementor-widget__width-inherit wdt-cst-main-pro-detail elementor-invisible elementor-widget elementor-widget-wdt-shop-product-single-summary\" data-id=\"e3bdeed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-summary.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ab6e8f8 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ab6e8f8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c5b3fc7\" data-id=\"c5b3fc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d82d8a elementor-widget__width-auto elementor-widget elementor-widget-wdt-shop-product-single-summary\" data-id=\"3d82d8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-product-single-summary.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1eb892f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1eb892f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bdde4cf elementor-invisible\" data-id=\"bdde4cf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e14ef7 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"8e14ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Guarantee safe and secure checkout<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8377a34 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"8377a34\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"510\" height=\"30\" src=\"https:\/\/maisonellej.co.uk\/wp-content\/uploads\/2023\/12\/shop-payment-4.png\" class=\"attachment-full size-full wp-image-2646\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2304760 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2304760\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ae94cfa elementor-invisible\" data-id=\"ae94cfa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65ab701 start wdt-cst-single-sidefaq elementor-widget elementor-widget-wdt-accordion-and-toggle\" data-id=\"65ab701\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-accordion-and-toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-accordion-toggle-holder wdt-module-toggle wdt-template-default wdt-expand-collapse-position-end\" id=\"wdt-accordion-and-toggle-65ab701\"><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Description<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 5.1 9\" style=\"enable-background:new 0 0 5.1 9;\" xml:space=\"preserve\"><path d=\"M0.2,8c-0.2,0.2-0.2,0.6,0,0.9c0.2,0.2,0.6,0.2,0.9,0l3.9-3.9c0.2-0.2,0.2-0.6,0-0.9L1,0.2c-0.2-0.2-0.6-0.2-0.9,0 c-0.2,0.2-0.2,0.6,0,0.9l3.5,3.5L0.2,8z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\"><path d=\"M95.38,33.93,54.52,74.79a6.35,6.35,0,0,1-9,0L4.62,33.93a6.41,6.41,0,0,1,9.09-9L50,61.19l36.29-36.3a6.41,6.41,0,1,1,9.09,9Z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Please provide product id to display corresponding data!<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Free Shipping &amp; Returns<\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 5.1 9\" style=\"enable-background:new 0 0 5.1 9;\" xml:space=\"preserve\"><path d=\"M0.2,8c-0.2,0.2-0.2,0.6,0,0.9c0.2,0.2,0.6,0.2,0.9,0l3.9-3.9c0.2-0.2,0.2-0.6,0-0.9L1,0.2c-0.2-0.2-0.6-0.2-0.9,0 c-0.2,0.2-0.2,0.6,0,0.9l3.5,3.5L0.2,8z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\"><path d=\"M95.38,33.93,54.52,74.79a6.35,6.35,0,0,1-9,0L4.62,33.93a6.41,6.41,0,0,1,9.09-9L50,61.19l36.29-36.3a6.41,6.41,0,1,1,9.09,9Z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Donec sed lectus mi. Vestibulum et augue ultricies, tempus augue non, consectetur est. In arcu justo, pulvinar sit amet turpis id, tincidunt fermentum eros. Nam porttitor massa ac leo porta congue nec at leo. Maecenas rutrum, neque bibendum vestibulum imperdiet, ex tellus molestie ante, at semper justo neque vel nisi. In tellus felis, suscipit pellentesque imperdiet sit amet, posuere nec sem. Sed at fringilla justo. Fusce dictum condimentum turpis vitae interdum.<\/div><\/div><div class=\"wdt-accordion-toggle-wrapper\"><div class=\"wdt-accordion-toggle-title-holder\"><div class=\"wdt-accordion-toggle-title\">Review <\/div><div class=\"wdt-accordion-toggle-icon\"><div class=\"wdt-accordion-toggle-icon-expand\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 5.1 9\" style=\"enable-background:new 0 0 5.1 9;\" xml:space=\"preserve\"><path d=\"M0.2,8c-0.2,0.2-0.2,0.6,0,0.9c0.2,0.2,0.6,0.2,0.9,0l3.9-3.9c0.2-0.2,0.2-0.6,0-0.9L1,0.2c-0.2-0.2-0.6-0.2-0.9,0 c-0.2,0.2-0.2,0.6,0,0.9l3.5,3.5L0.2,8z\"><\/path><\/svg><\/div><div class=\"wdt-accordion-toggle-icon-collapse\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\"><path d=\"M95.38,33.93,54.52,74.79a6.35,6.35,0,0,1-9,0L4.62,33.93a6.41,6.41,0,0,1,9.09-9L50,61.19l36.29-36.3a6.41,6.41,0,1,1,9.09,9Z\"><\/path><\/svg><\/div><\/div><\/div><div class=\"wdt-accordion-toggle-description\">Please provide product id to display corresponding data!<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f3ac8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f3ac8c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d027b83\" data-id=\"d027b83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0bda63c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0bda63c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;wdt_bg_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_laptop&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile_extra&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;wdt_bg_position&quot;:&quot;center center&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5d5bd30\" data-id=\"5d5bd30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-017704a elementor-widget-tablet_extra__width-initial elementor-widget-tablet__width-inherit elementor-widget__width-inherit center elementor-invisible elementor-widget elementor-widget-wdt-heading\" data-id=\"017704a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wdt-heading-holder \" id=\"wdt-heading-017704a\"><div class=\"wdt-heading-subtitle-wrapper wdt-heading-align-center \"><span class=\"wdt-heading-subtitle\">Glamorous Life<\/span><\/div><h3 class=\"wdt-heading-title-wrapper wdt-heading-align-center wdt-heading-deco-wrapper\"><span class=\"wdt-heading-title\">Elevate Your Style<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42528e3 elementor-invisible elementor-widget elementor-widget-wdt-shop-related-products\" data-id=\"42528e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;wdt_animation_effect&quot;:&quot;none&quot;}\" data-widget_type=\"wdt-shop-related-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\tPlease provide product id to display corresponding data!\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fusce laoreet nunc vitae tellus sodales rutrum quis et lacus.<br \/>\nSed ac leo tincidunt, gravida augue id, blandit massa.<\/p>\n","protected":false},"featured_media":3211,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":[],"product_brand":[],"product_cat":[45,52,54],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-2723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fashion-wear","7":"product_cat-long-dress","8":"product_cat-maxi-gowns","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple","15":"product-grid-view"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/product\/2723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=2723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/media\/3211"}],"wp:attachment":[{"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=2723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/product_brand?post=2723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/product_cat?post=2723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/product_tag?post=2723"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/maisonellej.co.uk\/index.php\/wp-json\/wp\/v2\/giftcard-category?post=2723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}